{"id":19854,"date":"2024-12-12T15:31:54","date_gmt":"2024-12-12T13:31:54","guid":{"rendered":"https:\/\/verusplus.gr\/microsoft\/dynamics-365-business-central\/"},"modified":"2025-02-26T16:05:47","modified_gmt":"2025-02-26T14:05:47","slug":"dynamics-365-business-central","status":"publish","type":"page","link":"https:\/\/verusplus.gr\/en\/microsoft\/dynamics-365-business-central\/","title":{"rendered":"Dynamics 365 Business Central"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"19854\" class=\"elementor elementor-19854\" data-elementor-post-type=\"page\">\r\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e626107 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"e626107\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7b9971a\" data-id=\"7b9971a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66f1f1f elementor-widget elementor-widget-heading\" data-id=\"66f1f1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Business Central Consulting<\/h1>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-6a1f8e0 elementor-widget elementor-widget-heading\" data-id=\"6a1f8e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Grow your business quickly with Dynamics 365 Business Central<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-2f368a6 elementor-widget elementor-widget-heading\" data-id=\"2f368a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The No.1 ERP worldwide from Microsoft <\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-c193889 elementor-widget elementor-widget-text-editor\" data-id=\"c193889\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/verusplus.gr\/en\/microsoft\/\">Microsoft<\/a> Dynamics 365 Business Central is the tool you need to get your business where it deserves to be &#8211; at the top. It allows you to comprehensively manage your company from one place, covering every need. Fully integrate the ERP with Microsoft 365, leverage Copilot&#8217;s artificial intelligence across your company, and break every productivity record.  <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-ea794c2 elementor-widget elementor-widget-button\" data-id=\"ea794c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#cta\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Speak with an expert<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-27144d0\" data-id=\"27144d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db6ce08 elementor-widget elementor-widget-image\" data-id=\"db6ce08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/microsoft-dynamics-365-business-central-1.png\" class=\"attachment-full size-full wp-image-14406\" alt=\"\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/microsoft-dynamics-365-business-central-1.png 700w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/microsoft-dynamics-365-business-central-1-300x214.png 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/microsoft-dynamics-365-business-central-1-105x75.png 105w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/microsoft-dynamics-365-business-central-1-480x343.png 480w\" sizes=\"(max-width:767px) 480px, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dfd80fc elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dfd80fc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7230aee\" data-id=\"7230aee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dc845f elementor-widget elementor-widget-heading\" data-id=\"3dc845f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ERP with proven results<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f666383 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"f666383\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-425b795\" data-id=\"425b795\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b4f5991 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b4f5991\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4058a2a\" data-id=\"4058a2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83d7ce1 elementor-widget elementor-widget-counter\" data-id=\"83d7ce1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\r\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\r\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\r\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"172\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\r\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">%<\/span>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-914bb49 elementor-widget elementor-widget-heading\" data-id=\"914bb49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ROI within 3 years<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-6dc4211 elementor-widget elementor-widget-counter\" data-id=\"6dc4211\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\r\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\r\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\r\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"30000\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\r\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">\u20ac<\/span>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-e8aa640 elementor-widget elementor-widget-heading\" data-id=\"e8aa640\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Savings per year on third party fees<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-38bbbb7\" data-id=\"38bbbb7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-820c2c8 elementor-widget elementor-widget-counter\" data-id=\"820c2c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\r\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\r\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\r\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"18\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\r\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">%<\/span>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-b1ed1e7 elementor-widget elementor-widget-heading\" data-id=\"b1ed1e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Productivity improvement<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-b5480e0 elementor-widget elementor-widget-counter\" data-id=\"b5480e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\r\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\r\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\r\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"7\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\r\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"> Months<\/span>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-4e6197e elementor-widget elementor-widget-heading\" data-id=\"4e6197e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Average payback time<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a66e0eb\" data-id=\"a66e0eb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-258df10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"258df10\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-aa41353\" data-id=\"aa41353\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8debfc4 elementor-widget elementor-widget-image\" data-id=\"8debfc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central.jpg\" class=\"attachment-large size-large wp-image-14430\" alt=\"\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central.jpg 600w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-300x200.jpg 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-113x75.jpg 113w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-480x320.jpg 480w\" sizes=\"(max-width:767px) 480px, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-52165d5\" data-id=\"52165d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4d247e elementor-widget elementor-widget-heading\" data-id=\"c4d247e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">&gt;40.000<\/p>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-b955108 elementor-widget elementor-widget-heading\" data-id=\"b955108\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">businesses are already using Microsoft Dynamics 365 Business Central<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-02ab641 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"02ab641\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2929c76\" data-id=\"2929c76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-531a67e elementor-widget elementor-widget-text-editor\" data-id=\"531a67e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"id-31\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p><em>\u03a0\u03b7\u03b3\u03ad\u03c2: <\/em><a href=\"https:\/\/go.microsoft.com\/fwlink\/?LinkId=2228016&amp;clcid=0x409&amp;culture=en-us&amp;country=us\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Break into new markets with Business Central, Nucleus Research<\/span><\/a><\/p>\n<p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/go.microsoft.com\/fwlink\/?linkid=2253105&amp;clcid=0x409&amp;culture=en-us&amp;country=us\" target=\"_blank\" rel=\"noopener\">See how customers realize ROI with Business Central, Forrester<\/a><\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-f81c67c elementor-widget elementor-widget-spacer\" data-id=\"f81c67c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9dc5a9 elementor-section-full_width elementor-section-stretched elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"c9dc5a9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1be38ce\" data-id=\"1be38ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e15488 elementor-widget elementor-widget-heading\" data-id=\"1e15488\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Simplify your work with Copilot<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-30300a0 elementor-widget elementor-widget-heading\" data-id=\"30300a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">The next generation AI with<br>everyday impact on your business<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-dfad3d3 elementor-widget elementor-widget-text-editor\" data-id=\"dfad3d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/verusplus.gr\/en\/microsoft\/copilot\/\">Copilot<\/a><\/span> is not just an LLM that presents information it finds on the internet. Instead, it acts as an extra worker for your business that solves questions, automates time-consuming processes and saves valuable time from searching and analyzing data. Some of Copilot&#8217;s features:  <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e2c910 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e2c910\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-954c506\" data-id=\"954c506\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a80d168 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a80d168\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-user\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Employee onboarding<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-bcf1f8d elementor-widget elementor-widget-text-editor\" data-id=\"bcf1f8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>With Copilot, your new staff members adapt faster than ever before. They ask simple questions in natural language and copilot shows them step-by-step the process they need to follow. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-967f775 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"967f775\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-search\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Information Search<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-814c470 elementor-widget elementor-widget-text-editor\" data-id=\"814c470\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Are you looking for specific documents or items among hundreds of records? Just describe what you are looking for and Copilot finds it for you. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f04a2c5\" data-id=\"f04a2c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03e7d52 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"03e7d52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-database\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Data analysis<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-9d22ad8 elementor-widget elementor-widget-text-editor\" data-id=\"9d22ad8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>You no longer need to spend time on time-consuming data analysis. Copilot analyses large volumes of data in seconds and provides you with the conclusions you need. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-5bc27d9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5bc27d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"far fa-file-alt\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Content creation<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-18907ca elementor-widget elementor-widget-text-editor\" data-id=\"18907ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Copilot creates attractive descriptions for your products based on their information in business central. You choose the features you want to emphasize, style and structure and Copilot produces the result. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30045a6\" data-id=\"30045a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a67ed6 e-transform elementor-widget elementor-widget-image\" data-id=\"6a67ed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.69999999999999996,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"187\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/copilot-logo.webp\" class=\"attachment-large size-large wp-image-14419\" alt=\"copilot-logo\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/copilot-logo.webp 600w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/copilot-logo-300x94.webp 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/copilot-logo-150x47.webp 150w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/copilot-logo-480x150.webp 480w\" sizes=\"(max-width:767px) 480px, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-e6df0a3 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"e6df0a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\r\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\r\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/copilot-use-cases-e1733821695681.png\" alt=\"copilot use cases: staff onboarding\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/copilot-in-business-central-e1733824885736.png\" alt=\"copilot \u03c3\u03c4\u03bf business central\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/copilot-in-dynamics-365.png\" alt=\"copilot in dynamics 365\" \/><\/figure><\/div>\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\r\n\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/em>\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\r\n\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/em>\t\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24fd1f1 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24fd1f1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9637c8\" data-id=\"b9637c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e36febb elementor-widget elementor-widget-spacer\" data-id=\"e36febb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-57196e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57196e4\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d5b636\" data-id=\"0d5b636\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf1bfbb elementor-widget elementor-widget-heading\" data-id=\"bf1bfbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Business Central and Microsoft 365<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-2ace54b elementor-widget elementor-widget-heading\" data-id=\"2ace54b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Take advantage of Dynamics' advanced integration with Microsoft 365 and skyrocket your productivity<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-11a9d68 elementor-widget elementor-widget-text-editor\" data-id=\"11a9d68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Dynamics and <a href=\"https:\/\/verusplus.gr\/en\/microsoft\/microsoft-365\/\">Microsoft 365<\/a> work seamlessly together, allowing you to complete tasks while dramatically reducing application switching time. Here are just a few of the ways in which 365 empowers Dynamics: <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0ed74c elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"b0ed74c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c6b0ae3\" data-id=\"c6b0ae3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f6bd92 elementor-widget elementor-widget-heading\" data-id=\"0f6bd92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">With Teams:<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-c2621b2 elementor-widget elementor-widget-image\" data-id=\"c2621b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"170\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-and-microsoft-teams.png\" class=\"attachment-large size-large wp-image-14440\" alt=\"\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-and-microsoft-teams.png 400w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-and-microsoft-teams-300x128.png 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-and-microsoft-teams-150x64.png 150w\" sizes=\"(max-width:767px) 400px, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-42b21a8 elementor-widget elementor-widget-text-editor\" data-id=\"42b21a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>With Business Central and Microsoft Teams you can share ERP data with your team and edit it within Teams. Even non-users of Business Central can view data received through Teams. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-91b9210\" data-id=\"91b9210\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ddc721 elementor-widget elementor-widget-heading\" data-id=\"8ddc721\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">With Outlook:<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-7b50734 elementor-widget elementor-widget-image\" data-id=\"7b50734\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"170\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-and-microsoft-outlook.png\" class=\"attachment-large size-large wp-image-14445\" alt=\"\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-and-microsoft-outlook.png 400w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-and-microsoft-outlook-300x128.png 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-and-microsoft-outlook-150x64.png 150w\" sizes=\"(max-width:767px) 400px, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-bdb21d0 elementor-widget elementor-widget-text-editor\" data-id=\"bdb21d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Go from quote to cash through Outlook, while also updating the customer in BC. Automate order confirmation emails and payment reminders. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1fc5f07\" data-id=\"1fc5f07\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71a3bc0 elementor-widget elementor-widget-heading\" data-id=\"71a3bc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">With Excel:<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-e5aca44 elementor-widget elementor-widget-image\" data-id=\"e5aca44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"170\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-and-microsoft-excel.png\" class=\"attachment-large size-large wp-image-14448\" alt=\"\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-and-microsoft-excel.png 400w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-and-microsoft-excel-300x128.png 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-and-microsoft-excel-150x64.png 150w\" sizes=\"(max-width:767px) 400px, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-9c1442b elementor-widget elementor-widget-text-editor\" data-id=\"9c1442b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Now you can export your data from Microsoft Dynamics to Excel, edit it, and with a few clicks, bring it back into the ERP.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3fac60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3fac60\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a606040\" data-id=\"a606040\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4e9bf1 elementor-widget elementor-widget-spacer\" data-id=\"d4e9bf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c03efc0 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"c03efc0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c7ae24c\" data-id=\"c7ae24c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c581bc elementor-widget elementor-widget-heading\" data-id=\"2c581bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">With Microsoft's ERP and 365:<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-e242a89 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e242a89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-laptop\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Minimize application switching time<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-sort-amount-up\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Unlock new levels of productivity<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-users\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cooperate closer than ever before<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e09f60a\" data-id=\"e09f60a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67f6ac2 elementor-pagination-position-inside elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"67f6ac2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\r\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\r\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/teams-and-business-central.png\" alt=\"teams and d365\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/outlook-and-business-central.png\" alt=\"outlook and business central\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/excel-and-business-central.png\" alt=\"excel and business central\" \/><\/figure><\/div>\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\r\n\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/em>\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\r\n\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/em>\t\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3efeba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3efeba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aee8763\" data-id=\"aee8763\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6758730 elementor-widget elementor-widget-spacer\" data-id=\"6758730\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26abf8c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26abf8c\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8485e6b\" data-id=\"8485e6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-935e9e3 elementor-widget elementor-widget-heading\" data-id=\"935e9e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Business Central Services<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f15397 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"9f15397\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-77e8560\" data-id=\"77e8560\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34efa80 elementor-widget elementor-widget-heading\" data-id=\"34efa80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Business Central Implementation<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-0660398 elementor-widget elementor-widget-text-editor\" data-id=\"0660398\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>We undertake the complete implementation of Business Central, adapting it to the specific needs of your business. We focus on a smooth transition from existing systems and ensure that the new platform works effectively from day one. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7db89c6\" data-id=\"7db89c6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e46ec4d elementor-widget elementor-widget-spacer\" data-id=\"e46ec4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d6edb9 elementor-section-full_width elementor-section-stretched elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"0d6edb9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-66cd0c0\" data-id=\"66cd0c0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db17811 elementor-widget elementor-widget-spacer\" data-id=\"db17811\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a3a5cf0\" data-id=\"a3a5cf0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a26942 elementor-widget elementor-widget-heading\" data-id=\"7a26942\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Business Central Customization<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-5a202e8 elementor-widget elementor-widget-text-editor\" data-id=\"5a202e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Each business operates in its own unique way. We customize Business Central with additional features, forms, fields and workflows to perfectly meet your needs and enhance the way you work. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4bbe250 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"4bbe250\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3a16545\" data-id=\"3a16545\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7baedb elementor-widget elementor-widget-heading\" data-id=\"e7baedb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Business Central Integration<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-138e970 elementor-widget elementor-widget-text-editor\" data-id=\"138e970\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>We integrate Business Central with third-party software or internal applications (e.g. CRM, eCommerce, warehouse systems), ensuring automatic data flow and overall improvement of business processes.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b387e68\" data-id=\"b387e68\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c599967 elementor-widget elementor-widget-spacer\" data-id=\"c599967\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7638996 elementor-section-full_width elementor-section-stretched elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"7638996\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b1781a3\" data-id=\"b1781a3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0c844c elementor-widget elementor-widget-spacer\" data-id=\"f0c844c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b51eb8e\" data-id=\"b51eb8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04c8a40 elementor-widget elementor-widget-heading\" data-id=\"04c8a40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Business Central Migration<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-73b38f8 elementor-widget elementor-widget-text-editor\" data-id=\"73b38f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>We take care of the migration from your old commercial software to business central, ensuring the complete and secure transfer of data, affecting daily operations as little as possible.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f34158 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"9f34158\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9e8d1d0\" data-id=\"9e8d1d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25e2124 elementor-widget elementor-widget-heading\" data-id=\"25e2124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Business Central Support<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-1dedfd4 elementor-widget elementor-widget-text-editor\" data-id=\"1dedfd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>We provide continuous monitoring and support of the system, addressing technical difficulties and performance issues immediately. With regular updates and optimizations, we ensure the stable and secure operation of Business Central. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0c20b86\" data-id=\"0c20b86\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-632e1a4 elementor-widget elementor-widget-spacer\" data-id=\"632e1a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae0f547 elementor-section-full_width elementor-section-stretched elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"ae0f547\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0b8e4ad\" data-id=\"0b8e4ad\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04c53df elementor-widget elementor-widget-spacer\" data-id=\"04c53df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a38b2a0\" data-id=\"a38b2a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73b85bb elementor-widget elementor-widget-heading\" data-id=\"73b85bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Business Central Consulting<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-e049f46 elementor-widget elementor-widget-text-editor\" data-id=\"e049f46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Leveraging our years of experience in Microsoft technologies and business process redesign, we analyze your needs and recommend efficient ways to work smarter and improve your company&#8217;s results.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c30866 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"7c30866\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e372a9e\" data-id=\"e372a9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e62ddcf elementor-widget elementor-widget-heading\" data-id=\"e62ddcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Business Central Development<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-3c496e7 elementor-widget elementor-widget-text-editor\" data-id=\"3c496e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Our dedicated programming department develops new features, designed around your unique needs, extending BC. In doing so, we allow you to innovate and intelligently redesign your workflows. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-da02b80\" data-id=\"da02b80\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-125a300 elementor-widget elementor-widget-spacer\" data-id=\"125a300\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd75400 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd75400\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-189d37f\" data-id=\"189d37f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-179b18a elementor-widget elementor-widget-heading\" data-id=\"179b18a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Benefits of D365 Business Central for your business<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-3b525c8 elementor-widget elementor-widget-heading\" data-id=\"3b525c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">With Business Central, you free up time to focus on activities of greater value to your company and your customers<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1753b09 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"1753b09\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-402d566\" data-id=\"402d566\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25eb2bf elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"25eb2bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-briefcase\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Evolve your business<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-3ccc9a6 elementor-widget elementor-widget-text-editor\" data-id=\"3ccc9a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>With Dynamics BC you work smarter than ever, speed up your processes and elevate your business.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-181f724 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"181f724\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-cogs\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Automate processes<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-2294cb1 elementor-widget elementor-widget-text-editor\" data-id=\"2294cb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Connecting to M365, Power Platform and Copilot, help you automate critical processes and get more done in less time.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-52ed61e elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"52ed61e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-euro-sign\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Increase profitability<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-4873bbd elementor-widget elementor-widget-text-editor\" data-id=\"4873bbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Save valuable time from time-consuming processes and make smart decisions based on Copilot data and insights.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-977a1fc elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"977a1fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-users\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Make the most of your people's potential<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-1cdd39e elementor-widget elementor-widget-text-editor\" data-id=\"1cdd39e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>New employees are adapting faster than ever before, and are having an immediate impact. They don&#8217;t get bogged down in time-consuming processes, they focus on what they do best. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1e967d1\" data-id=\"1e967d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b6fd9e elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0b6fd9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-fast-forward\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">You benefit immediately<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-c82c68d elementor-widget elementor-widget-text-editor\" data-id=\"c82c68d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>It has an immediate impact on your daily work, with incremental applications that your staff can easily use.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-8ed9c2b elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8ed9c2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-database\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Secure your data<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-b5c6a35 elementor-widget elementor-widget-text-editor\" data-id=\"b5c6a35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Your data is stored in the <a href=\"https:\/\/verusplus.gr\/en\/microsoft\/azure\/\">Azure Cloud<\/a>, ensuring it is kept secure and preventing cyber-attacks and leaks.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-6d0f3a8 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6d0f3a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-mobile-alt\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Work from anywhere<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-1348f2c elementor-widget elementor-widget-text-editor\" data-id=\"1348f2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Work from anywhere, with access to Business Central from desktop, tablet and mobile.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-b81aa58 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b81aa58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-project-diagram\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Improve communication<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-731b131 elementor-widget elementor-widget-text-editor\" data-id=\"731b131\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Integrated with Office, it provides you with a unified management of your company, improving collaboration and information sharing.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5a3fe9b\" data-id=\"5a3fe9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce015d8 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ce015d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-user-edit\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cover every need<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-e8128af elementor-widget elementor-widget-text-editor\" data-id=\"e8128af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Business Central is fully customizable to your unique needs, so you can work in the best way for your business.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-cecf4f3 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"cecf4f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-user-cog\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">You adapt instantly<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-97089b6 elementor-widget elementor-widget-text-editor\" data-id=\"97089b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Dynamics is one of the easiest to use ERPs on the market, with intuitive UI\/UX and navigation with Copilot.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-d0973f5 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d0973f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-tree\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Operate sustainably<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-c35e4b5 elementor-widget elementor-widget-text-editor\" data-id=\"c35e4b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>You monitor and manage sustainability indicators effectively.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-78e623c elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"78e623c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\r\n\t\t\t\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-briefcase\"><\/em>\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Connection to third party systems<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-f8c41c1 elementor-widget elementor-widget-text-editor\" data-id=\"f8c41c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Fully integrate D365 BC with your existing applications to streamline your processes without completely altering the way you work.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cbfd24 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cbfd24\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5590ac1\" data-id=\"5590ac1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa19888 elementor-widget elementor-widget-spacer\" data-id=\"aa19888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c62687 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c62687\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b41ebd2\" data-id=\"b41ebd2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1232a7 elementor-widget elementor-widget-heading\" data-id=\"e1232a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Functions of Dynamics 365 Business Central<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-05a044e elementor-widget elementor-widget-text-editor\" data-id=\"05a044e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Dynamics 365 Business Central covers every need of your business, from finance and supply chain to sales and services:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-995f8e7 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"995f8e7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ac4fd44\" data-id=\"ac4fd44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5930c7 elementor-widget elementor-widget-heading\" data-id=\"a5930c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Finance<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-bbc1b30 elementor-widget elementor-widget-image\" data-id=\"bbc1b30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"615\" height=\"410\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-finance.jpg\" class=\"attachment-large size-large wp-image-14536\" alt=\"dynamics 365 business central finance\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-finance.jpg 615w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-finance-300x200.jpg 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-finance-113x75.jpg 113w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/dynamics-365-business-central-finance-480x320.jpg 480w\" sizes=\"(max-width:767px) 480px, 615px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-081612a elementor-widget elementor-widget-accordion\" data-id=\"081612a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-8471\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8471\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">General Accounting and Dimensions<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-8471\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8471\"><p>Microsoft Business Central allows general ledger management through tools such as general journal, reports in multiple currencies, and dimensions. Dimensions are used to categorize data, such as departments and projects, with the ability to apply rules for data reliability and use default values. <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-8472\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-8472\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Multiple Currencies and Budgets<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-8472\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-8472\"><p>It supports multi-currency transactions for sales, purchases and banking. Offers functions for creating and analyzing budgets, with the ability to import and export data via Excel for more flexibility. <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-8473\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-8473\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Fixed and Deferred Income\/Expenses<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-8473\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-8473\"><p>Full tracking of fixed assets, with the ability to calculate depreciation, record maintenance costs and track insurance coverage. Recognition of income and expenses in different periods through standard deferrals. <\/p>\n<h3> <\/h3>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-8474\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-8474\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Cash Management and Reconciliations<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-8474\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-8474\"><p>Cash flow management includes liquidity forecasting, electronic payments, automatic bank reconciliation, and cheque management. Functions for bank account reconciliations are integrated, with the possibility of automatic data entry and application of matching rules. <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-15fa685\" data-id=\"15fa685\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0a7944 elementor-widget elementor-widget-heading\" data-id=\"d0a7944\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Supply chain<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-9253296 elementor-widget elementor-widget-image\" data-id=\"9253296\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"615\" height=\"410\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/supply-chain-management-in-dynamics-365-business-central-1.jpg\" class=\"attachment-large size-large wp-image-14541\" alt=\"supply chain management in dynamics 365 business central\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/supply-chain-management-in-dynamics-365-business-central-1.jpg 615w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/supply-chain-management-in-dynamics-365-business-central-1-300x200.jpg 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/supply-chain-management-in-dynamics-365-business-central-1-113x75.jpg 113w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/supply-chain-management-in-dynamics-365-business-central-1-480x320.jpg 480w\" sizes=\"(max-width:767px) 480px, 615px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-4f3a84b elementor-widget elementor-widget-accordion\" data-id=\"4f3a84b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-8301\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8301\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Purchase Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-8301\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8301\"><p>Facilitates the management of purchases through functions such as invoicing, order management and returns. It supports the creation of prepayments, invoice discounts and management of multiple order addresses. Users can utilize alternative suppliers and catalogs for out-of-stock products.  <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-8302\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-8302\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Inventory Control and Data Analysis<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-8302\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-8302\"><p>Provides capabilities for managing inventory across multiple locations, product categories, item characteristics and tracking by serial or batch numbers. Users can perform inventory analyses, manage inventory cycles and accurately schedule deliveries. <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-8303\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-8303\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Supply Chain Planning and Availability<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-8303\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-8303\"><p>With tools such as demand forecasting, material planning and transfer management, Business Central optimises the supply flow. These functions include support for assembly, production and supply orders, as well as integration of AI technologies for sales and inventory forecasting. <\/p>\n<h3> <\/h3>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-8304\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-8304\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Order and Availability Support<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-8304\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-8304\"><p>Users can manage deliveries based on product availability and promise accurate shipping dates. Third-party shipments, tracking of costs and profits per order, and instant stock availability updates are supported to enhance accuracy and customer service. <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-242d17d\" data-id=\"242d17d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8da7b66 elementor-widget elementor-widget-heading\" data-id=\"8da7b66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Production<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-eef19de elementor-widget elementor-widget-image\" data-id=\"eef19de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"610\" height=\"407\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/manufacturing-dynamics-365-business-central.jpg\" class=\"attachment-large size-large wp-image-14545\" alt=\"manufacturing dynamics 365 business central\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/manufacturing-dynamics-365-business-central.jpg 610w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/manufacturing-dynamics-365-business-central-300x200.jpg 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/manufacturing-dynamics-365-business-central-112x75.jpg 112w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/manufacturing-dynamics-365-business-central-480x320.jpg 480w\" sizes=\"(max-width:767px) 480px, 610px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-f4445e3 elementor-widget elementor-widget-accordion\" data-id=\"f4445e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2561\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2561\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Optimisation of Manufacturing Operations<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2561\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2561\"><p>Dynamics 365 Business Central enhances the functionality in industrial production, enabling the improvement of quality, productivity and availability of production lines. At the same time, it reduces costs and ensures that you meet your customers&#8217; expectations. <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2562\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2562\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Management of Material and Resource Sets<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2562\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2562\"><p>The creation of a list of assembly materials, products and raw materials is supported through &#8220;assembly bills of materials&#8221;. Assembly orders meet customer requirements directly from quotations and orders, while the cost management tool provides a reliable method of maintaining accurate stock prices. <\/p>\n<h3> <\/h3>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2563\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2563\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Production Planning and Capacity Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2563\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2563\"><p>Capacities such as work centres and machines ensure efficient order routing and material planning. At the same time, it includes the creation of production orders, variation management and needs analysis through automatic or manual planning tools. <\/p>\n<h3> <\/h3>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2564\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2564\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Subcontracting and Waste Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2564\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2564\"><p>The system provides tools for outsourcing work to external work centres, tracking raw materials and recording work produced through purchase orders. In addition, scrap recording ensures accurate costing and inventory management, minimising waste and improving resource management. <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4eda367 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"4eda367\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3ec72dc\" data-id=\"3ec72dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fd3846 elementor-widget elementor-widget-heading\" data-id=\"2fd3846\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sales<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-8dddec8 elementor-widget elementor-widget-image\" data-id=\"8dddec8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"307\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/sales-dynamics-365-business-central.jpg\" class=\"attachment-large size-large wp-image-14549\" alt=\"\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/sales-dynamics-365-business-central.jpg 460w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/sales-dynamics-365-business-central-300x200.jpg 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/sales-dynamics-365-business-central-112x75.jpg 112w\" sizes=\"(max-width:767px) 460px, 460px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-f8a6625 elementor-widget elementor-widget-accordion\" data-id=\"f8a6625\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2601\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2601\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Unified Contact and Campaign Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2601\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2601\"><p>Business Central allows you to manage contacts and campaigns in a unified environment. Capture business relationship information, organize contacts into categories based on profiles and weighted criteria, and personalize your communications. Create and manage campaigns for targeted contact segments, reusing ready-made criteria and sending messages in different languages.  <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2602\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2602\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Advanced Selling Tools<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2602\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2602\"><p>Track and manage sales opportunities through a structured staging system. Create quotes, orders, and invoices easily, and you can set customized prices and discounts based on customer needs. Offer the best possible price with automatic price calculations and discounts, while managing orders that include prepayments or partial shipments.  <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2603\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2603\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Returns and Shipment Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2603\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2603\"><p>Efficiently address product return needs by creating return orders for customers who received defective or incorrect products. Add multiple shipping addresses for customers who maintain multiple pickup points, allowing for flexible and fast service. <\/p>\n<h3> <\/h3>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2604\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2604\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Integration with Microsoft 365<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2604\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2604\"><p>Benefit from Business Central&#8217;s tight integration with Microsoft Outlook and Dynamics 365 Sales for a smooth flow of data from initial contact to sales completion. Automatically capture all your interactions, including emails, phone calls, and orders, and you can do bulk billing through Microsoft Bookings for greater ease of sales management. <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6515d64\" data-id=\"6515d64\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54196ad elementor-widget elementor-widget-heading\" data-id=\"54196ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Project management<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-f58c858 elementor-widget elementor-widget-image\" data-id=\"f58c858\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"307\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/project-management-dynamics-365-business-central.jpg\" class=\"attachment-large size-large wp-image-14553\" alt=\"project management dynamics 365 business central\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/project-management-dynamics-365-business-central.jpg 460w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/project-management-dynamics-365-business-central-300x200.jpg 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/project-management-dynamics-365-business-central-112x75.jpg 112w\" sizes=\"(max-width:767px) 460px, 460px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-d794aee elementor-widget elementor-widget-accordion\" data-id=\"d794aee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2261\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2261\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Successful Project Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2261\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2261\"><p>It provides integrated solutions to execute projects successfully, enhancing profitability through real-time planning, monitoring, billing and analysis. With resource, time and cost management tools, it ensures effective project management from inception to completion. <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2262\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2262\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Resource and Capacity Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2262\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2262\"><p>Monitor resources and prices, splitting resources into labour and equipment. Create resource pools for greater convenience and plan their use on specific projects. Capacity planning and usage statistics provide a comprehensive view of availability and profitability through an easy-to-use calendar system.  <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2263\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2263\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Comprehensive Project Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2263\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2263\"><p>Manage projects on a fixed cost basis or on an hourly and material basis. Create detailed project plans, set budgets per task and track progress via multiple currencies. Use tools like the Settings Wizard and Project Manager Role Center for easy access to critical functions and reports, such as sending customer quotes.  <\/p>\n<h3> <\/h3>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2264\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2264\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Time Tracking and Billing Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2264\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2264\"><p>With the simple and flexible Time Sheet feature, record the time spent on projects and ensure manager approval. Integration with the Service and Project Management functions allows for comprehensive resource and time management, contributing to accuracy and transparency when tracking and billing work. <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c57fb26\" data-id=\"c57fb26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-543dcf3 elementor-widget elementor-widget-heading\" data-id=\"543dcf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Services<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-7cd5f3d elementor-widget elementor-widget-image\" data-id=\"7cd5f3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"307\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/services-dynamics-365-business-central.jpg\" class=\"attachment-large size-large wp-image-14557\" alt=\"\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/services-dynamics-365-business-central.jpg 460w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/services-dynamics-365-business-central-300x200.jpg 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/services-dynamics-365-business-central-112x75.jpg 112w\" sizes=\"(max-width:767px) 460px, 460px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-f1354bb elementor-widget elementor-widget-accordion\" data-id=\"f1354bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2521\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2521\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Human Resource Planning and Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2521\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2521\"><p>With BC you can plan and manage the allocation of staff for maintenance and repair work. Record details of each task, such as its status and handling. For assignments, filter available personnel based on skills, availability, and necessary materials, gaining clear insight into priorities and workloads.  <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2522\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2522\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Service Contract Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2522\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2522\"><p>Organize service agreements with your customers, including service levels, historical contracts, and renewal standards. Track details such as response times, discount levels, and maintenance history for each contract. Manage equipment and parts warranties, and you can measure contract profitability and create quotes for new contracts.  <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2523\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2523\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Equipment Management and Performance Analysis<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2523\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2523\"><p>Record and track all service items, including contract, parts, and warranty information. Use the <strong>Trendscape<\/strong> Analysis feature to view critical performance indicators of service items during different periods to identify trends and improvements. <\/p>\n<h3> <\/h3>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2524\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2524\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Service Order Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2524\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2524\"><p>Address after-sales issues by recording maintenance requests, repairs, and service orders. Automatically create contract-based requests or let customers submit them. Provide equipment on loan and track order history through <strong>Service Order Log<\/strong> for data completeness and service optimization.  <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-fa9c422\" data-id=\"fa9c422\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a117599 elementor-widget elementor-widget-heading\" data-id=\"a117599\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Warehouse management<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-79c7364 elementor-widget elementor-widget-image\" data-id=\"79c7364\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"307\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/warehouse-management-in-dynamics-365-business-central.jpg\" class=\"attachment-large size-large wp-image-14560\" alt=\"warehouse management in dynamics 365 business central\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/warehouse-management-in-dynamics-365-business-central.jpg 460w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/warehouse-management-in-dynamics-365-business-central-300x200.jpg 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/warehouse-management-in-dynamics-365-business-central-112x75.jpg 112w\" sizes=\"(max-width:767px) 460px, 460px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-d16f2a1 elementor-widget elementor-widget-accordion\" data-id=\"d16f2a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2191\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2191\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Inventory Level Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2191\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2191\"><p>Adapt your warehouse processes to the needs of each location. Choose whether to use bins and whether tasks will be performed with separate documents or directly update sales and purchase orders. Determine whether picking and shipping processes will be done in separate steps or in one movement.  <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2192\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2192\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Organisation and Position Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2192\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2192\"><p>Create an organised warehouse structure by defining bins for each product, the smallest unit in the logical structure of the warehouse. Configure the bins based on the warehouse layout, shelf dimensions and storage needs. Predefined locations speed up document processing and help to better plan needs.  <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2193\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2193\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Receipts and Shipments Management<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2193\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2193\"><p>Use a separate interface to manage receipts and shipments in a multi-order environment. Create pickups from purchase orders and shipments from sales orders, with the ability to process multiple documents simultaneously. Pick lists and storage instructions make it easy for the warehouse team to perform tasks.  <\/p>\n<h3> <\/h3>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2194\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2194\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Directed Selection and Storage<\/a>\r\n\t\t\t\t\t<\/h4>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-2194\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2194\"><p>Automate the picking and storage process according to placement patterns and location classifications. Use zones and location rankings to improve picking flow and use of available space. Take advantage of cross-docking to reduce time and address different units of measure for the same products.  <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-726dc76 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"726dc76\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-99342fc\" data-id=\"99342fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8396d53 elementor-widget elementor-widget-spacer\" data-id=\"8396d53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b66cbc elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b66cbc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c3c5416\" data-id=\"c3c5416\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96680cf elementor-widget elementor-widget-heading\" data-id=\"96680cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Business Central and Power Platform<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-7a3559b elementor-widget elementor-widget-heading\" data-id=\"7a3559b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Take advantage of Power Platform's industry-leading technologies combined with Business Central and work smarter than ever<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-6b28296 elementor-widget elementor-widget-text-editor\" data-id=\"6b28296\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Here are a few ways in which Business Central integrates with <a href=\"https:\/\/verusplus.gr\/en\/microsoft\/power-platform\/\">Power Platform<\/a>:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd2c0f6 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"fd2c0f6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c0b6ad0\" data-id=\"c0b6ad0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b923ec3 elementor-widget elementor-widget-heading\" data-id=\"b923ec3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">With Power Apps:<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-2691b4b elementor-widget elementor-widget-image\" data-id=\"2691b4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"170\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-power-apps.png\" class=\"attachment-large size-large wp-image-14639\" alt=\"business central and powe\u03c1 apps\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-power-apps.png 400w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-power-apps-300x128.png 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-power-apps-150x64.png 150w\" sizes=\"(max-width:767px) 400px, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-c913ca7 elementor-widget elementor-widget-text-editor\" data-id=\"c913ca7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>With <a href=\"https:\/\/verusplus.gr\/en\/microsoft\/power-platform\/power-apps\/\">Power Apps<\/a> we create specialized applications that extend the functionality of Business Central even further.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8c31cce\" data-id=\"8c31cce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a90b30e elementor-widget elementor-widget-heading\" data-id=\"a90b30e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">With Power Automate:<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-1c6152e elementor-widget elementor-widget-image\" data-id=\"1c6152e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"170\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-power-automate.png\" class=\"attachment-large size-large wp-image-14644\" alt=\"business central and power automate\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-power-automate.png 400w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-power-automate-300x128.png 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-power-automate-150x64.png 150w\" sizes=\"(max-width:767px) 400px, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-7828ab9 elementor-widget elementor-widget-text-editor\" data-id=\"7828ab9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Use <a href=\"https:\/\/verusplus.gr\/en\/microsoft\/power-platform\/power-automate\/\">Power Automate<\/a> in conjunction with Business Central to automate critical workflows and save valuable man-hours every day. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-fd9be84\" data-id=\"fd9be84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a4d800 elementor-widget elementor-widget-heading\" data-id=\"2a4d800\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">With Power BI:<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-1743621 elementor-widget elementor-widget-image\" data-id=\"1743621\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"170\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-power-bi.png\" class=\"attachment-large size-large wp-image-14648\" alt=\"\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-power-bi.png 400w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-power-bi-300x128.png 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-power-bi-150x64.png 150w\" sizes=\"(max-width:767px) 400px, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-490b253 elementor-widget elementor-widget-text-editor\" data-id=\"490b253\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>With <a href=\"https:\/\/verusplus.gr\/en\/microsoft\/power-platform\/power-bi\/\">Power BI<\/a>, you create meaningful reports from Dynamics BC data in real time. Draw valuable conclusions and make smart decisions. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d50be0d\" data-id=\"d50be0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e01306f elementor-widget elementor-widget-heading\" data-id=\"e01306f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">With Copilot Studio:<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-1044aba elementor-widget elementor-widget-image\" data-id=\"1044aba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"170\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-copilot-studio-1.png\" class=\"attachment-large size-large wp-image-14655\" alt=\"business central and copilot studio\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-copilot-studio-1.png 400w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-copilot-studio-1-300x128.png 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-and-copilot-studio-1-150x64.png 150w\" sizes=\"(max-width:767px) 400px, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-dce2678 elementor-widget elementor-widget-text-editor\" data-id=\"dce2678\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Enhance the daily life of your staff and customers by creating specialized copilots (digital assistants) through <a href=\"https:\/\/verusplus.gr\/en\/microsoft\/power-platform\/copilot-studio\/\">Copilot Studio<\/a>. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9bd967f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9bd967f\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33796d8\" data-id=\"33796d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3182554 elementor-widget elementor-widget-spacer\" data-id=\"3182554\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9cfe692 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9cfe692\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c2e44eb\" data-id=\"c2e44eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdfb86b elementor-widget elementor-widget-heading\" data-id=\"cdfb86b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Satisfies the needs of all the company's people<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e49806d elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"e49806d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0be9e11\" data-id=\"0be9e11\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b92fe0 elementor-widget elementor-widget-heading\" data-id=\"3b92fe0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Entrepreneur<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-b892935 elementor-widget elementor-widget-image\" data-id=\"b892935\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"253\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-for-entrepreneurs.jpg\" class=\"attachment-full size-full wp-image-14999\" alt=\"business central for entrepreneurs\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-for-entrepreneurs.jpg 380w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-for-entrepreneurs-300x200.jpg 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-for-entrepreneurs-113x75.jpg 113w\" sizes=\"(max-width:767px) 380px, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-5b625ec elementor-widget elementor-widget-text-editor\" data-id=\"5b625ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Choose the solution that can make a difference in just a few weeks. Business Central is the ERP that grows your business and returns your initial investment in 7 months. It helps you launch new products quickly and reduce risk while increasing profitability.  <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e762900\" data-id=\"e762900\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8157d5 elementor-widget elementor-widget-heading\" data-id=\"e8157d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">IT<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-839ed90 elementor-widget elementor-widget-image\" data-id=\"839ed90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"253\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-for-it-managers.jpg\" class=\"attachment-full size-full wp-image-15001\" alt=\"\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-for-it-managers.jpg 380w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-for-it-managers-300x200.jpg 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-for-it-managers-113x75.jpg 113w\" sizes=\"(max-width:767px) 380px, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-9caa1ee elementor-widget elementor-widget-text-editor\" data-id=\"9caa1ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Business Central is an integrated solution that can be easily integrated into any business and improves the daily lives of employees. No longer does IT have to worry about security or speed issues, or complex deployments and upgrades. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-174baaf\" data-id=\"174baaf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-647a365 elementor-widget elementor-widget-heading\" data-id=\"647a365\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Employees<\/h3>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-19f11ad elementor-widget elementor-widget-image\" data-id=\"19f11ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"253\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-benefits-for-users.jpg\" class=\"attachment-full size-full wp-image-15003\" alt=\"\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-benefits-for-users.jpg 380w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-benefits-for-users-300x200.jpg 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/business-central-benefits-for-users-113x75.jpg 113w\" sizes=\"(max-width:767px) 380px, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-0aca27d elementor-widget elementor-widget-text-editor\" data-id=\"0aca27d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>With Business Central, your employees are not bogged down in manual processes, but focus on the things that make a difference. Copilot&#8217;s ease of use and support allows new and old employees alike to quickly adapt to new processes and be productive. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-981ebca elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"981ebca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-afdd8f7\" data-id=\"afdd8f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f1c14a elementor-widget elementor-widget-spacer\" data-id=\"0f1c14a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f9fdf6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f9fdf6\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3dca5b4\" data-id=\"3dca5b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78bcdd5 elementor-widget elementor-widget-heading\" data-id=\"78bcdd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Why Verus+ is the ideal Dynamics 365 Business Central partner<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ace039 elementor-section-full_width elementor-section-stretched elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"8ace039\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-999d924\" data-id=\"999d924\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6868442 elementor-widget elementor-widget-text-editor\" data-id=\"6868442\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Verus+, with over 15 years of experience in Microsoft technologies, is the right partner to successfully implement Dynamics 365 Business Central in your business processes. Having delivered dozens of business software projects across a wide range of economic activity, we can understand the specific needs of your business and implement solutions based on Microsoft technologies through small, iterative development cycles. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-c4cb19b elementor-widget elementor-widget-button\" data-id=\"c4cb19b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:+302310452262\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Call us today<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e332f4e\" data-id=\"e332f4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6426fc4 elementor-widget elementor-widget-image\" data-id=\"6426fc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"112\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/verus-microsoft-dynamics-365-business-central-e1733916141637.png\" class=\"attachment-large size-large wp-image-14615\" alt=\"verus+ microsoft dynamics 365 business central\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/verus-microsoft-dynamics-365-business-central-e1733916141637.png 850w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/verus-microsoft-dynamics-365-business-central-e1733916141637-300x40.png 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/verus-microsoft-dynamics-365-business-central-e1733916141637-768x101.png 768w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/verus-microsoft-dynamics-365-business-central-e1733916141637-150x20.png 150w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/verus-microsoft-dynamics-365-business-central-e1733916141637-480x63.png 480w\" sizes=\"(max-width:767px) 480px, (max-width:850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b7e66c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7e66c0\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-033ccec\" data-id=\"033ccec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-100991a elementor-widget elementor-widget-spacer\" data-id=\"100991a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-473740f elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"473740f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d3d4c8d\" data-id=\"d3d4c8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8eddae elementor-widget elementor-widget-menu-anchor\" data-id=\"d8eddae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"cta\"><\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-7e21dbd elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7e21dbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\r\n\r\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\r\n\t\t\t\t<span  class=\"elementor-icon\">\r\n\t\t\t\t<em aria-hidden=\"true\" class=\"fas fa-laptop-code\"><\/em>\t\t\t\t<\/span>\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\r\n\t\t\t\t\t\t<span  >\r\n\t\t\t\t\t\t\tBook Free Consultation\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t<\/h2>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-fe9778a elementor-widget elementor-widget-text-editor\" data-id=\"fe9778a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t<p>Fill in the form and one of our qualified consultants will contact you directly to arrange an appointment at which:<\/p>\n<ul>\n<li>We will analyse your needs<\/li>\n<li>We will present Business Central in action<\/li>\n<li>We will recommend the next steps for successful ERP implementation<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-0d486d1 elementor-widget elementor-widget-image\" data-id=\"0d486d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"255\" src=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/verusplus-business-central-partners-1.png\" class=\"attachment-full size-full wp-image-14697\" alt=\"\" srcset=\"https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/verusplus-business-central-partners-1.png 600w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/verusplus-business-central-partners-1-300x128.png 300w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/verusplus-business-central-partners-1-150x64.png 150w, https:\/\/verusplus.gr\/wp-content\/uploads\/2024\/12\/verusplus-business-central-partners-1-480x204.png 480w\" sizes=\"(max-width:767px) 480px, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-930ac6c\" data-id=\"930ac6c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f766f6 elementor-widget elementor-widget-wpforms\" data-id=\"2f766f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpforms.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<div class=\"wpforms-container wpforms-render-modern\" id=\"wpforms-1214\"><form id=\"wpforms-form-1214\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"1214\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/19854\" data-token=\"92adffd957b8bfcc761dc46afc4bd26e\" data-token-time=\"1788369196\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-1214-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-1214-field_1\">\u039f\u03bd\u03bf\u03bc\u03b1\u03c4\u03b5\u03c0\u03ce\u03bd\u03c5\u03bc\u03bf <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1214-field_1\" class=\"wpforms-field-large wpforms-field-required wpforms-limit-characters-enabled\" data-form-id=\"1214\" data-field-id=\"1\" data-text-limit=\"150\" name=\"wpforms[fields][1]\" aria-errormessage=\"wpforms-1214-field_1-error\" maxlength=\"150\" required><\/div><div id=\"wpforms-1214-field_3-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-1214-field_3\">\u0395\u03c0\u03b1\u03b3\u03b3\u03b5\u03bb\u03bc\u03b1\u03c4\u03b9\u03ba\u03cc Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1214-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" spellcheck=\"false\" aria-errormessage=\"wpforms-1214-field_3-error\" required><\/div><div id=\"wpforms-1214-field_4-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-1214-field_4\">\u03a4\u03b7\u03bb\u03ad\u03c6\u03c9\u03bd\u03bf <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-1214-field_4\" class=\"wpforms-field-large wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][4]\" aria-label=\"\u03a4\u03b7\u03bb\u03ad\u03c6\u03c9\u03bd\u03bf\" aria-errormessage=\"wpforms-1214-field_4-error\" required><\/div><div id=\"wpforms-1214-field_9-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-type=\"textarea\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-1214-field_9\">\u03a0\u03b5\u03c1\u03b9\u03b3\u03c1\u03ac\u03c8\u03c4\u03b5 \u03c4\u03b7\u03bd \u03b1\u03bd\u03ac\u03b3\u03ba\u03b7 \u03c3\u03b1\u03c2<\/label><textarea id=\"wpforms-1214-field_9\" class=\"wpforms-field-medium\" name=\"wpforms[fields][9]\" aria-errormessage=\"wpforms-1214-field_9-error\" ><\/textarea><\/div><div id=\"wpforms-1214-field_10-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"10\"><label class=\"wpforms-field-label\">\u03a3\u03c5\u03bd\u03b1\u03af\u03bd\u03b5\u03c3\u03b7 \u03bc\u03b5 \u03c4\u03bf \u0393\u03b5\u03bd\u03b9\u03ba\u03cc \u039a\u03b1\u03bd\u03bf\u03bd\u03b9\u03c3\u03bc\u03cc \u03a0\u03c1\u03bf\u03c3\u03c9\u03c0\u03b9\u03ba\u03ce\u03bd \u0394\u03b5\u03b4\u03bf\u03bc\u03ad\u03bd\u03c9\u03bd <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-1214-field_10\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-1214-field_10_1\" name=\"wpforms[fields][10][]\" value=\"\u03a3\u03c5\u03bc\u03c6\u03c9\u03bd\u03ce \u03c3\u03c4\u03b7\u03bd \u03b5\u03c0\u03b5\u03be\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1 \u03c4\u03c9\u03bd \u03c0\u03c1\u03bf\u03c3\u03c9\u03c0\u03b9\u03ba\u03ce\u03bd \u03bc\u03bf\u03c5 \u03b4\u03b5\u03b4\u03bf\u03bc\u03ad\u03bd\u03c9\u03bd \u03c3\u03cd\u03bc\u03c6\u03c9\u03bd\u03b1 \u03bc\u03b5 \u03c4\u03bf\u03c5\u03c2 \u03cc\u03c1\u03bf\u03c5\u03c2 \u03c0\u03bf\u03c5 \u03b1\u03bd\u03b1\u03c6\u03ad\u03c1\u03bf\u03bd\u03c4\u03b1\u03b9 \u03c3\u03c4\u03b7\u03bd \u03c0\u03bf\u03bb\u03b9\u03c4\u03b9\u03ba\u03ae \u03c0\u03c1\u03bf\u03c3\u03c4\u03b1\u03c3\u03af\u03b1\u03c2\" aria-errormessage=\"wpforms-1214-field_10_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1214-field_10_1\">\u03a3\u03c5\u03bc\u03c6\u03c9\u03bd\u03ce \u03c3\u03c4\u03b7\u03bd \u03b5\u03c0\u03b5\u03be\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1 \u03c4\u03c9\u03bd \u03c0\u03c1\u03bf\u03c3\u03c9\u03c0\u03b9\u03ba\u03ce\u03bd \u03bc\u03bf\u03c5 \u03b4\u03b5\u03b4\u03bf\u03bc\u03ad\u03bd\u03c9\u03bd \u03c3\u03cd\u03bc\u03c6\u03c9\u03bd\u03b1 \u03bc\u03b5 \u03c4\u03bf\u03c5\u03c2 \u03cc\u03c1\u03bf\u03c5\u03c2 \u03c0\u03bf\u03c5 \u03b1\u03bd\u03b1\u03c6\u03ad\u03c1\u03bf\u03bd\u03c4\u03b1\u03b9 \u03c3\u03c4\u03b7\u03bd \u03c0\u03bf\u03bb\u03b9\u03c4\u03b9\u03ba\u03ae \u03c0\u03c1\u03bf\u03c3\u03c4\u03b1\u03c3\u03af\u03b1\u03c2<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1214\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/verusplus.gr\/en\/wp-json\/wp\/v2\/pages\/19854\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1214\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"\u03a5\u03c0\u03bf\u03b2\u03bf\u03bb\u03ae\" aria-live=\"assertive\" value=\"wpforms-submit\">\u03a5\u03c0\u03bf\u03b2\u03bf\u03bb\u03ae<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/verusplus.gr\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-303c842 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"303c842\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-51829cd\" data-id=\"51829cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-768c9e2 elementor-widget elementor-widget-heading\" data-id=\"768c9e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Frequently asked questions about Business Central<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-b442ad2 elementor-widget elementor-widget-accordion\" data-id=\"b442ad2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1891\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1891\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">What is Dynamics 365 Business Central?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-1891\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1891\"><p data-start=\"0\" data-end=\"267\">Microsoft Dynamics 365 Business Central is an integrated cloud ERP solution that covers financial management, trading, inventory and project functions, specifically designed for small and medium-sized businesses.<\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1892\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1892\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">How is Business Central used?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-1892\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1892\"><ul data-start=\"324\" data-end=\"582\">\n<li data-start=\"324\" data-end=\"374\">Management of financial and accounting operations<\/li>\n<li data-start=\"375\" data-end=\"429\">Inventory and supply chain monitoring<\/li>\n<li data-start=\"430\" data-end=\"469\">Automation of sales processes<\/li>\n<li data-start=\"470\" data-end=\"509\">Project and budget management<\/li>\n<li data-start=\"510\" data-end=\"582\">Centralised information for better business decisions<\/li>\n<\/ul>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1893\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1893\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">How much does Business Central cost?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-1893\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1893\"><p data-start=\"1013\" data-end=\"1063\">The cost is based on a monthly subscription, with different plans (Essentials or Premium), depending on the features your business needs. The final price varies depending on additional licenses, applications and support services. <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1894\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1894\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Why should I choose Business Central?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-1894\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1894\"><ul>\n<li data-start=\"926\" data-end=\"986\">Comprehensive integration of artificial intelligence<\/li>\n<li data-start=\"926\" data-end=\"986\">Single platform for all business operations<\/li>\n<li data-start=\"987\" data-end=\"1026\">Easy expansion and configuration<\/li>\n<li data-start=\"1027\" data-end=\"1073\">Integration with the Microsoft 365 ecosystem<\/li>\n<li data-start=\"1074\" data-end=\"1121\">Real-time reporting and analysis capabilities<\/li>\n<li data-start=\"1122\" data-end=\"1173\">Cloud infrastructure for maximum flexibility and security<\/li>\n<\/ul>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1895\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1895\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">What are the modules of Business Central?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-1895\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1895\"><ul>\n<li>Finance<\/li>\n<li>Supply chain<\/li>\n<li>Production<\/li>\n<li>Sales<\/li>\n<li>Project management<\/li>\n<li>Services<\/li>\n<li>Warehouse management<\/li>\n<\/ul>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1896\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1896\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">How do I get Business Central?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-1896\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1896\"><p>You can get Business Central through an official Microsoft partner such as Verus+. Contact us to analyze your needs and get started with the configuration and installation of the software. <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1897\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1897\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Which Microsoft 365 applications connect to Business Central?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-1897\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1897\"><ul>\n<li data-start=\"2537\" data-end=\"2548\">Outlook<\/li>\n<li data-start=\"2549\" data-end=\"2563\">SharePoint<\/li>\n<li data-start=\"2564\" data-end=\"2573\">Teams<\/li>\n<li data-start=\"2574\" data-end=\"2586\">OneDrive<\/li>\n<li data-start=\"2587\" data-end=\"2596\">Excel<\/li>\n<li data-start=\"2587\" data-end=\"2596\">Word<\/li>\n<li data-start=\"2587\" data-end=\"2596\">Powerpoint<\/li>\n<\/ul>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1898\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1898\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Is there a free trial for BC?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-1898\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1898\"><p>Yes. Microsoft offers a 30-day free trial of Business Central to evaluate the key features and usefulness for your business. Contact us to get started with your free trial of Business Central.  <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1899\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1899\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Why should I trust the cloud?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-1899\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1899\"><ul>\n<li data-start=\"2231\" data-end=\"2291\">Flexibility to scale based on business growth<\/li>\n<li data-start=\"2292\" data-end=\"2357\">Continuous updates and improvements without downtime<\/li>\n<li data-start=\"2358\" data-end=\"2406\">Integrated safety and compliance measures<\/li>\n<li data-start=\"2407\" data-end=\"2463\">Ease of access from anywhere, anytime<\/li>\n<\/ul>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-18910\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-18910\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Which Microsoft products does it work with?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-18910\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-18910\"><p>In addition to Microsoft 365 (Office, Outlook, Teams), Business Central is fully integrated with other Dynamics 365 products (Sales, etc.) and the Power Platform (Power BI, Power Apps, Power Automate).<\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-18911\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-18911\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Is Dynamics 365 BC easy to use?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-18911\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-18911\"><p>Yes. It has a friendly interface with simple menus. Copilot AI performs tasks, provides guidance and helps with navigation and information search, making BC particularly easy to use. In addition, it offers personalized user roles for quick access to necessary functions.   <\/p>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-18912\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-18912\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">What support does Verus+ provide for Business Central?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-18912\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-18912\"><ul data-start=\"3054\" data-end=\"3264\">\n<li data-start=\"3054\" data-end=\"3101\">Needs analysis and tailored implementation<\/li>\n<li data-start=\"3102\" data-end=\"3155\">Data migration and system configuration<\/li>\n<li data-start=\"3156\" data-end=\"3207\">User training and consulting<\/li>\n<li data-start=\"3208\" data-end=\"3264\">Continuous technical support and ERP optimization<\/li>\n<\/ul>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-18913\" class=\"elementor-tab-title\" data-tab=\"13\" role=\"button\" aria-controls=\"elementor-tab-content-18913\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">How does BC differ from other ERP solutions?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-18913\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"13\" role=\"region\" aria-labelledby=\"elementor-tab-title-18913\"><ul>\n<li data-start=\"3330\" data-end=\"3378\">Intrinsic integration into the Microsoft ecosystem (365, Power Platform, Azure)<\/li>\n<li data-start=\"3330\" data-end=\"3378\">Use of artificial intelligence in all operations<\/li>\n<li data-start=\"3379\" data-end=\"3426\">Flexibility in configuration and scaling<\/li>\n<li data-start=\"3427\" data-end=\"3483\">Offers real-time reports and advanced analytics<\/li>\n<li data-start=\"3484\" data-end=\"3541\">Seamless connectivity with Microsoft cloud services<\/li>\n<\/ul>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\r\n\t\t\t\t\t<h3 id=\"elementor-tab-title-18914\" class=\"elementor-tab-title\" data-tab=\"14\" role=\"button\" aria-controls=\"elementor-tab-content-18914\" aria-expanded=\"false\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><em class=\"fas fa-plus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><em class=\"fas fa-minus\"><\/em><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">How is data security ensured?<\/a>\r\n\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t<div id=\"elementor-tab-content-18914\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"14\" role=\"region\" aria-labelledby=\"elementor-tab-title-18914\"><ul>\n<li data-start=\"3602\" data-end=\"3666\">Hosting on Microsoft Azure with advanced security standards<\/li>\n<li data-start=\"3667\" data-end=\"3721\">Data encryption<\/li>\n<li data-start=\"3722\" data-end=\"3779\">Strict compliance with international standards (GDPR, ISO etc.)<\/li>\n<li data-start=\"3780\" data-end=\"3849\" data-is-last-node=\"\">Regular security updates and patches from Microsoft<\/li>\n<\/ul>\n<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>Business Central Consulting Grow your business quickly with Dynamics 365 Business Central The No.1 ERP worldwide from Microsoft Microsoft Dynamics 365 Business Central is the tool<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":1271,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-19854","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/verusplus.gr\/en\/wp-json\/wp\/v2\/pages\/19854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verusplus.gr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/verusplus.gr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/verusplus.gr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/verusplus.gr\/en\/wp-json\/wp\/v2\/comments?post=19854"}],"version-history":[{"count":20,"href":"https:\/\/verusplus.gr\/en\/wp-json\/wp\/v2\/pages\/19854\/revisions"}],"predecessor-version":[{"id":20723,"href":"https:\/\/verusplus.gr\/en\/wp-json\/wp\/v2\/pages\/19854\/revisions\/20723"}],"up":[{"embeddable":true,"href":"https:\/\/verusplus.gr\/en\/wp-json\/wp\/v2\/pages\/1271"}],"wp:attachment":[{"href":"https:\/\/verusplus.gr\/en\/wp-json\/wp\/v2\/media?parent=19854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}